{"id":729,"count":1,"description":"","link":"https:\/\/exchangerateweb.com\/es\/tag\/libyan-currency-exchange\/","name":"Cambio de divisas libio","slug":"cambio-de-moneda-libia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/exchangerateweb.com\/es\/wp-json\/wp\/v2\/tags\/729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exchangerateweb.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/exchangerateweb.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/exchangerateweb.com\/es\/wp-json\/wp\/v2\/posts?tags=729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}