{"id":485,"count":1,"description":"","link":"https:\/\/exchangerateweb.com\/de\/tag\/belarusian-ruble-exchange-rate\/","name":"Wechselkurs des belarussischen Rubels","slug":"wechselkurs-des-belarussischen-rubels","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/exchangerateweb.com\/de\/wp-json\/wp\/v2\/tags\/485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exchangerateweb.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/exchangerateweb.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/exchangerateweb.com\/de\/wp-json\/wp\/v2\/posts?tags=485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}